{"id":7155,"date":"2019-11-21T10:25:49","date_gmt":"2019-11-21T09:25:49","guid":{"rendered":"https:\/\/bellevue.novaresa.website\/camere\/"},"modified":"2026-05-05T16:15:20","modified_gmt":"2026-05-05T14:15:20","slug":"camere","status":"publish","type":"page","link":"https:\/\/www.hotel-lebellevue.fr\/it\/camere\/","title":{"rendered":"Camere"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f1f1f1&#8243; bg_image=&#8221;7398&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;15%&#8221; bottom_padding=&#8221;7%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;inner-head&#8221; id=&#8221;en-tete&#8221; color_overlay=&#8221;#0a0a0a&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#f1f1f1&#8243; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;curve&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#ffffff&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Camere&#8221; font_container=&#8221;tag:h1|text_align:center|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_column_text]\n<p style=\"text-align: center;\">Nos chambres, toutes lumineuses et d\u00e9cor\u00e9es avec soin, offrent une ambiance m\u00e9diterran\u00e9enne apaisante.<br \/>\nCertaines b\u00e9n\u00e9ficient d\u2019une <strong data-start=\"1977\" data-end=\"2000\">vue panoramique mer<\/strong>, parfaites pour un r\u00e9veil face au lever du soleil.<br \/>\nChaque chambre est \u00e9quip\u00e9e de climatisation, Wifi gratuit, t\u00e9l\u00e9vision et terrasse privative pour un confort optimal.<br \/>\nNos chambres sont pr\u00e9vues pour accueillir 2 personnes; possibilit\u00e9 d&#8217;ajouter un lit d&#8217;appoint pour un enfant jusqu&#8217;\u00e0 14 ans.<\/p>\n<p style=\"text-align: center;\">Les chambres en \u00e9tage sont accessibles par ascenseur.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;7%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;7%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#51a393&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#ffffff&#8221; column_shadow=&#8221;small_depth&#8221; column_border_radius=&#8221;5px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text]\n<h2>Chambre<br \/>\nStandard<br \/>\n<span style=\"font-size: 34px;\">A partir de 75,00 \u20ac<\/span><\/h2>\n[\/vc_column_text][vc_column_text]Id\u00e9ales pour deux personnes, nos chambres standard sont confortables et id\u00e9ales en solo ou en couple.<br \/>\nAcc\u00e8s et chambre PMR possible, pr\u00e9cisez-nous le.<\/p>\n<ul>\n<li>Chambre avec terrasse<\/li>\n<li>Equipements : Lit King-size (ou 2 lits s\u00e9par\u00e9s) \/ Climatisation \/ T\u00e9l\u00e9vision \/ Coffre-fort \/ Bureau \/ Wifi \/ Fauteuils sur la terrasse \/ Salle de bain avec baignoire ou douche \/ S\u00e8che-cheveux<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;7628&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Bottom&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;medium_depth&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;img-pano&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;7%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#51a393&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#ffffff&#8221; column_shadow=&#8221;small_depth&#8221; column_border_radius=&#8221;5px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text]\n<h2>Chambre Terrasse<br \/>\nVue Mer Partielle<br \/>\n<span style=\"font-size: 34px;\">A partir de 81,00 \u20ac<\/span><\/h2>\n[\/vc_column_text][vc_column_text]Parfaites pour un s\u00e9jour en bord de mer, nos chambres vue mer partielle situ\u00e9es au 1ier \u00e9tage de l&#8217;h\u00f4tel disposent d&#8217;un lit king-size et d&#8217;une salle de bain avec baignoire.<br \/>\nLa vue d\u00e9gag\u00e9e depuis votre lit ou votre terrasse invite au repos.<\/p>\n<ul>\n<li>Chambre avec terrasse<\/li>\n<li>Vue Mer partielle (1er \u00e9tage)<\/li>\n<li>Equipements : Lit King-size (ou 2 lits s\u00e9par\u00e9s) \/ Climatisation \/ T\u00e9l\u00e9vision \/ Coffre-fort \/ Bureau \/ Wifi \/ Fauteuils sur la terrasse \/ Salle de bain avec baignoire \/ WC s\u00e9par\u00e9 \/ S\u00e8che-cheveux<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;7649&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Bottom&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;medium_depth&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;img-pano&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;7%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#51a393&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#ffffff&#8221; column_shadow=&#8221;small_depth&#8221; column_border_radius=&#8221;5px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text]\n<h2>Chambre Terrasse<br \/>\nVue Mer<br \/>\n<span style=\"font-size: 34px;\">A partir de 91,00 \u20ac<\/span><\/h2>\n[\/vc_column_text][vc_column_text]Parfaites pour un s\u00e9jour prolong\u00e9, nos chambres sup\u00e9rieures disposent d&#8217;un lit king-size et d&#8217;une salle de bain avec baignoire.<br \/>\nSitu\u00e9es au 2\u00e8me \u00e9tage du b\u00e2timent, la vue sur la mer est imm\u00e9diate depuis votre lit ou votre terrasse.<\/p>\n<ul>\n<li>Chambre avec terrasse<\/li>\n<li>Vue sur la Mer<\/li>\n<li>Equipements : Lit King-size (ou 2 lits s\u00e9par\u00e9s) \/ Climatisation \/ T\u00e9l\u00e9vision \/ Coffre-fort \/ Bureau \/ Wifi \/ Fauteuils sur la terrasse \/ Salle de bain avec baignoire \/ WC s\u00e9par\u00e9 \/ S\u00e8che-cheveux<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;7633&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Bottom&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;medium_depth&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;img-pano&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;7%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#51a393&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#ffffff&#8221; column_shadow=&#8221;small_depth&#8221; column_border_radius=&#8221;5px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text]\n<h2>Chambre Terrasse<br \/>\nVue Mer \/ Douche<br \/>\n<span style=\"font-size: 34px;\">A partir de 93,00 \u20ac<\/span><\/h2>\n[\/vc_column_text][vc_column_text]Parfaites pour un s\u00e9jour prolong\u00e9, nos chambres sup\u00e9rieures r\u00e9cemment r\u00e9nov\u00e9es disposent d&#8217;un lit king-size, mini-frigo et d&#8217;une salle de bain avec douche \u00e0 l&#8217;italienne. Situato al 2\u00b0 piano dell&#8217;edificio, la vista sul mare \u00e8 immediata dal vostro letto o dalla terrazza.<\/p>\n<ul>\n<li>Chambre avec terrasse<\/li>\n<li>Vue sur la Mer<\/li>\n<li>Equipements : Lit King-size (ou 2 lits s\u00e9par\u00e9s) \/ Climatisation \/ Mini-frigo \/ T\u00e9l\u00e9vision \/ Coffre-fort \/ Bureau \/ Wifi \/ Fauteuils sur la terrasse \/ Salle de bain avec douche \u00e0 l&#8217;italienne \/ WC s\u00e9par\u00e9 \/ S\u00e8che-cheveux<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;7638&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Bottom&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;medium_depth&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;img-pano&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;7%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#d47b5d&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#ffffff&#8221; column_shadow=&#8221;small_depth&#8221; column_border_radius=&#8221;5px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text]\n<h2>Chambre Terrasse<br \/>\nVue Panoramique<br \/>\n<span style=\"font-size: 34px;\">A partir de 97,00 \u20ac<\/span><\/h2>\n[\/vc_column_text][vc_column_text]Avec une vue spectaculaire sur les falaises et la mer M\u00e9diterran\u00e9e, ces chambres r\u00e9cemment r\u00e9nov\u00e9es disposent d&#8217;un lit king size, d&#8217;un mini-frigo et d&#8217;une salle de bain avec douche \u00e0 l&#8217;italienne. E, naturalmente, c&#8217;\u00e8 una terrazza dove rilassarsi e ammirare la Grande Bleue!<\/p>\n<ul>\n<li>Chambre avec terrasse<\/li>\n<li>Vue sur la Mer<\/li>\n<li>Equipements : Lit King-size (ou 2 lits s\u00e9par\u00e9s) \/ Climatisation \/ Mini-frigo \/ T\u00e9l\u00e9vision \/ Coffre-fort \/ Bureau \/ Wifi \/ Fauteuils sur la terrasse \/ Salle de bain avec douche \u00e0 l&#8217;italienne \/ WC s\u00e9par\u00e9 \/ S\u00e8che-cheveux<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;7373&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Bottom&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;medium_depth&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;img-pano&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_global_section id=&#8221;6210&#8243;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f1f1f1&#8243; bg_image=&#8221;7398&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;15%&#8221; bottom_padding=&#8221;7%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;inner-head&#8221; id=&#8221;en-tete&#8221; color_overlay=&#8221;#0a0a0a&#8221; overlay_strength=&#8221;0.3&#8243;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-7155","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Camere - H\u00f4tel Le Bellevue<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hotel-lebellevue.fr\/it\/camere\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Camere - H\u00f4tel Le Bellevue\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f1f1f1&#8243; bg_image=&#8221;7398&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;15%&#8221; bottom_padding=&#8221;7%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;inner-head&#8221; id=&#8221;en-tete&#8221; color_overlay=&#8221;#0a0a0a&#8221; overlay_strength=&#8221;0.3&#8243;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hotel-lebellevue.fr\/it\/camere\/\" \/>\n<meta property=\"og:site_name\" content=\"H\u00f4tel Le Bellevue\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hotelplage\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T14:15:20+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.hotel-lebellevue.fr\/it\/camere\/\",\"url\":\"https:\/\/www.hotel-lebellevue.fr\/it\/camere\/\",\"name\":\"Camere - H\u00f4tel Le Bellevue\",\"isPartOf\":{\"@id\":\"https:\/\/www.hotel-lebellevue.fr\/#website\"},\"datePublished\":\"2019-11-21T09:25:49+00:00\",\"dateModified\":\"2026-05-05T14:15:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.hotel-lebellevue.fr\/it\/camere\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.hotel-lebellevue.fr\/it\/camere\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.hotel-lebellevue.fr\/it\/camere\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.hotel-lebellevue.fr\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Camere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.hotel-lebellevue.fr\/#website\",\"url\":\"https:\/\/www.hotel-lebellevue.fr\/\",\"name\":\"H\u00f4tel Le Bellevue\",\"description\":\"Un h\u00f4tel au Cap d&#039;Agde\",\"publisher\":{\"@id\":\"https:\/\/www.hotel-lebellevue.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.hotel-lebellevue.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.hotel-lebellevue.fr\/#organization\",\"name\":\"H\u00f4tel Bellevue\",\"url\":\"https:\/\/www.hotel-lebellevue.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.hotel-lebellevue.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.hotel-lebellevue.fr\/wp-content\/uploads\/2023\/03\/Bellevue-Hotel-Logo-Colored.png\",\"contentUrl\":\"https:\/\/www.hotel-lebellevue.fr\/wp-content\/uploads\/2023\/03\/Bellevue-Hotel-Logo-Colored.png\",\"width\":1699,\"height\":3514,\"caption\":\"H\u00f4tel Bellevue\"},\"image\":{\"@id\":\"https:\/\/www.hotel-lebellevue.fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/hotelplage\",\"https:\/\/www.instagram.com\/lebellevuehotel\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Camere - H\u00f4tel Le Bellevue","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hotel-lebellevue.fr\/it\/camere\/","og_locale":"it_IT","og_type":"article","og_title":"Camere - H\u00f4tel Le Bellevue","og_description":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f1f1f1&#8243; bg_image=&#8221;7398&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;15%&#8221; bottom_padding=&#8221;7%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;inner-head&#8221; id=&#8221;en-tete&#8221; color_overlay=&#8221;#0a0a0a&#8221; overlay_strength=&#8221;0.3&#8243;...","og_url":"https:\/\/www.hotel-lebellevue.fr\/it\/camere\/","og_site_name":"H\u00f4tel Le Bellevue","article_publisher":"https:\/\/www.facebook.com\/hotelplage","article_modified_time":"2026-05-05T14:15:20+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"13 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hotel-lebellevue.fr\/it\/camere\/","url":"https:\/\/www.hotel-lebellevue.fr\/it\/camere\/","name":"Camere - H\u00f4tel Le Bellevue","isPartOf":{"@id":"https:\/\/www.hotel-lebellevue.fr\/#website"},"datePublished":"2019-11-21T09:25:49+00:00","dateModified":"2026-05-05T14:15:20+00:00","breadcrumb":{"@id":"https:\/\/www.hotel-lebellevue.fr\/it\/camere\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hotel-lebellevue.fr\/it\/camere\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hotel-lebellevue.fr\/it\/camere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.hotel-lebellevue.fr\/it\/"},{"@type":"ListItem","position":2,"name":"Camere"}]},{"@type":"WebSite","@id":"https:\/\/www.hotel-lebellevue.fr\/#website","url":"https:\/\/www.hotel-lebellevue.fr\/","name":"H\u00f4tel Le Bellevue","description":"Un h\u00f4tel au Cap d&#039;Agde","publisher":{"@id":"https:\/\/www.hotel-lebellevue.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hotel-lebellevue.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.hotel-lebellevue.fr\/#organization","name":"H\u00f4tel Bellevue","url":"https:\/\/www.hotel-lebellevue.fr\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hotel-lebellevue.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.hotel-lebellevue.fr\/wp-content\/uploads\/2023\/03\/Bellevue-Hotel-Logo-Colored.png","contentUrl":"https:\/\/www.hotel-lebellevue.fr\/wp-content\/uploads\/2023\/03\/Bellevue-Hotel-Logo-Colored.png","width":1699,"height":3514,"caption":"H\u00f4tel Bellevue"},"image":{"@id":"https:\/\/www.hotel-lebellevue.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/hotelplage","https:\/\/www.instagram.com\/lebellevuehotel\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.hotel-lebellevue.fr\/it\/wp-json\/wp\/v2\/pages\/7155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hotel-lebellevue.fr\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hotel-lebellevue.fr\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hotel-lebellevue.fr\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hotel-lebellevue.fr\/it\/wp-json\/wp\/v2\/comments?post=7155"}],"version-history":[{"count":10,"href":"https:\/\/www.hotel-lebellevue.fr\/it\/wp-json\/wp\/v2\/pages\/7155\/revisions"}],"predecessor-version":[{"id":7724,"href":"https:\/\/www.hotel-lebellevue.fr\/it\/wp-json\/wp\/v2\/pages\/7155\/revisions\/7724"}],"wp:attachment":[{"href":"https:\/\/www.hotel-lebellevue.fr\/it\/wp-json\/wp\/v2\/media?parent=7155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}